{"id":98889,"date":"2026-07-15T13:13:08","date_gmt":"2026-07-15T13:13:08","guid":{"rendered":"https:\/\/ultimahora.mx\/index.php\/2026\/07\/15\/empresarios-aportan-nuevos-testimonios-contra-presunto-tirador-de-la-via-atlixcayotl-en-puebla\/"},"modified":"2026-07-15T19:13:10","modified_gmt":"2026-07-15T19:13:10","slug":"empresarios-aportan-nuevos-testimonios-contra-presunto-tirador-de-la-via-atlixcayotl-en-puebla","status":"publish","type":"post","link":"https:\/\/ultimahora.mx\/index.php\/2026\/07\/15\/empresarios-aportan-nuevos-testimonios-contra-presunto-tirador-de-la-via-atlixcayotl-en-puebla\/","title":{"rendered":"Empresarios aportan nuevos testimonios contra presunto tirador de la V\u00eda Atlixc\u00e1yotl en Puebla"},"content":{"rendered":"<p>El gobernador de Puebla, Alejandro Armenta, inform\u00f3 este mi\u00e9rcoles 15 de julio de 2026 que varios integrantes del sector empresarial han decidido colaborar con su administraci\u00f3n para aportar informaci\u00f3n relevante sobre hechos pasados que presuntamente involucran a Rafael N., se\u00f1alado como el presunto responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl.  <\/p>\n<p>En una rueda de prensa desde la Ciudad de M\u00e9xico, Armenta detall\u00f3 que una de estas personas, cuya identidad se mantiene bajo reserva legal, presentar\u00e1 formalmente su testimonio ante la Fiscal\u00eda General del Estado (FGE) para que sea integrado a la carpeta de investigaci\u00f3n.  <\/p>\n<p>El gobernador subray\u00f3 que ser\u00e1 la Fiscal\u00eda la autoridad encargada de determinar el alcance de esta nueva informaci\u00f3n y, en su caso, iniciar las investigaciones correspondientes.  <\/p>\n<p>Esta declaraci\u00f3n se produce un d\u00eda despu\u00e9s de la detenci\u00f3n de Rafael N., ocurrida el martes 14 de julio de 2026, quien enfrenta investigaciones por los ataques contra automovilistas en la V\u00eda Atlixc\u00e1yotl, un caso que contin\u00faa bajo integraci\u00f3n por parte de la Fiscal\u00eda poblana.  <\/p>\n<p>Armenta destac\u00f3 que la colaboraci\u00f3n de ciudadanos y empresarios es fundamental para el esclarecimiento de este caso que ha generado preocupaci\u00f3n entre los habitantes de Puebla, quienes exigen orden y seguridad en sus vialidades. Asimismo, reiter\u00f3 que su administraci\u00f3n mantendr\u00e1 una coordinaci\u00f3n estrecha con las autoridades ministeriales para que las indagatorias se desarrollen conforme a derecho, en un contexto donde la inseguridad urbana amenaza la tranquilidad y la funcionalidad de la ciudad.<\/p>\n<div class=\"embed-x\">\n<blockquote class=\"twitter-tweet\"><p>\n<a href=\"https:\/\/x.com\/Diario_Cambio\/status\/2077462232481345859\"><\/a>\n<\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>El gobernador de Puebla, Alejandro Armenta, inform\u00f3 este mi\u00e9rcoles 15 de julio de 2026 que varios integrantes del sector empresarial han decidido colaborar con su administraci\u00f3n para aportar informaci\u00f3n relevante sobre hechos pasados que presuntamente involucran a Rafael N., se\u00f1alado como el presunto responsable de los ataques armados en la V\u00eda Atlixc\u00e1yotl. En una rueda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98888,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-98889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=98889"}],"version-history":[{"count":1,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98889\/revisions"}],"predecessor-version":[{"id":98890,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98889\/revisions\/98890"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/media\/98888"}],"wp:attachment":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=98889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=98889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=98889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}