{"id":98751,"date":"2026-07-14T14:10:17","date_gmt":"2026-07-14T14:10:17","guid":{"rendered":"https:\/\/ultimahora.mx\/index.php\/2026\/07\/14\/diputados-exigen-a-secretaria-de-turismo-rendir-cuentas-tras-tragedia-en-grutas-de-chichicazapan\/"},"modified":"2026-07-14T20:10:20","modified_gmt":"2026-07-14T20:10:20","slug":"diputados-exigen-a-secretaria-de-turismo-rendir-cuentas-tras-tragedia-en-grutas-de-chichicazapan","status":"publish","type":"post","link":"https:\/\/ultimahora.mx\/index.php\/2026\/07\/14\/diputados-exigen-a-secretaria-de-turismo-rendir-cuentas-tras-tragedia-en-grutas-de-chichicazapan\/","title":{"rendered":"Diputados exigen a secretaria de Turismo rendir cuentas tras tragedia en grutas de Chichicazapan"},"content":{"rendered":"<p>La tragedia ocurrida en las grutas de Chichicazapan, en el municipio de Cuetzalan, donde cuatro integrantes de la familia Pe\u00f1a perdieron la vida al quedar atrapados durante un recorrido tur\u00edstico, ha desatado una ola de cuestionamientos sobre la seguridad y supervisi\u00f3n en los destinos de turismo de aventura en Puebla.  <\/p>\n<p>Ante estos hechos, la diputada local del PRI, Delfina Pozos Vergara, anunci\u00f3 que solicitar\u00e1 formalmente la comparecencia de la secretaria de Desarrollo Tur\u00edstico del estado, Carla L\u00f3pez-Malo Villal\u00f3n, ante el Congreso de Puebla. La legisladora exige que la funcionaria informe sobre las acciones, mecanismos de supervisi\u00f3n y protocolos aplicados para garantizar la seguridad de los visitantes en estos espacios.  <\/p>\n<p>En entrevista, Pozos Vergara subray\u00f3 la necesidad de esclarecer c\u00f3mo se vigila la operaci\u00f3n de agencias y prestadores de servicios tur\u00edsticos, especialmente en actividades de riesgo. \u201cLos poblanos y las poblanas necesitan saber qu\u00e9 fue lo que realmente pas\u00f3 en Cuetzalan. Es incongruente que no hayan previsto las condiciones climatol\u00f3gicas y que ahora sepamos que el gu\u00eda de turistas ni siquiera estaba dado de alta. \u00bfPor qu\u00e9 se permite que personas sin acreditaci\u00f3n tomen la responsabilidad de llevar visitantes y los expongan a estos riesgos?\u201d, cuestion\u00f3.  <\/p>\n<p>La diputada tambi\u00e9n pidi\u00f3 que se aclare bajo qu\u00e9 permisos operaba la agencia responsable del recorrido y si cumpl\u00eda con las disposiciones legales para ofrecer este tipo de actividades. Esta petici\u00f3n cobra fuerza luego de que el secretario de Gobernaci\u00f3n estatal, Samuel Aguilar Pala, informara que el gu\u00eda encargado de la expedici\u00f3n no contaba con una licencia oficial que lo acreditara como gu\u00eda tur\u00edstico.  <\/p>\n<p>Pozos Vergara insisti\u00f3 en que el Congreso debe conocer los planes de vigilancia y seguridad que existen en las zonas de turismo de aventura del estado, as\u00ed como las medidas que implementar\u00e1 la Secretar\u00eda de Desarrollo Tur\u00edstico para evitar que una tragedia similar vuelva a ocurrir.  <\/p>\n<p>Finalmente, la diputada reiter\u00f3 su compromiso con la transparencia y la rendici\u00f3n de cuentas de los funcionarios p\u00fablicos, al considerar que la ciudadan\u00eda merece conocer las responsabilidades y las acciones que emprender\u00e1 el gobierno estatal tras los hechos registrados en Cuetzalan.  <\/p>\n<p>Este llamado a la rendici\u00f3n de cuentas se produce en un contexto donde la seguridad y el orden en los espacios p\u00fablicos y tur\u00edsticos se vuelven cada vez m\u00e1s urgentes para preservar la confianza de los ciudadanos y visitantes, y evitar que la falta de regulaci\u00f3n y supervisi\u00f3n siga cobrando vidas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La tragedia ocurrida en las grutas de Chichicazapan, en el municipio de Cuetzalan, donde cuatro integrantes de la familia Pe\u00f1a perdieron la vida al quedar atrapados durante un recorrido tur\u00edstico, ha desatado una ola de cuestionamientos sobre la seguridad y supervisi\u00f3n en los destinos de turismo de aventura en Puebla. Ante estos hechos, la diputada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98750,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[16],"tags":[],"class_list":["post-98751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local"],"_links":{"self":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/comments?post=98751"}],"version-history":[{"count":1,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98751\/revisions"}],"predecessor-version":[{"id":98752,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/posts\/98751\/revisions\/98752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/media\/98750"}],"wp:attachment":[{"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/media?parent=98751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/categories?post=98751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ultimahora.mx\/index.php\/wp-json\/wp\/v2\/tags?post=98751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}